{"id":8696,"date":"2019-09-24T15:24:40","date_gmt":"2019-09-24T13:24:40","guid":{"rendered":"https:\/\/www.stelvision.com\/astro\/?page_id=8696"},"modified":"2023-04-27T14:33:30","modified_gmt":"2023-04-27T12:33:30","slug":"galeries-photo","status":"publish","type":"page","link":"https:\/\/www.stelvision.com\/astro\/galeries-photo\/","title":{"rendered":"Les plus belles photos astronomiques du concours Stelvision"},"content":{"rendered":"\n<p class=\"chapo wp-block-paragraph\">Offrez-vous un moment d&rsquo;\u00e9vasion gr\u00e2ce aux images que nous envoient les astrophotographes ! Les trois galeries \u00e0 d\u00e9couvrir ci-dessous sont renouvel\u00e9es progressivement avec les photos distingu\u00e9es par le jury dans le cadre de notre <a href=\"https:\/\/www.stelvision.com\/astro\/concours-photo\/\">concours semestriel<\/a>.<\/p>\n\n\n\n<p style=\"text-align:right\"><p style=\"text-align:right\" id=\"cat-ss\">cat\u00e9gories : <strong>Syst\u00e8me solaire<\/strong> | <a href=\"#cat-cp\">Ciel profond<\/a> | <a href=\"#cat-amb\">Ambiance <\/a><\/p>\n\n\n\n<hr class=\"wp-block-separator has-css-opacity\"\/>\n\n\n\n<h2 class=\"wp-block-heading\">Galerie Syst\u00e8me solaire<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><div class=\"rl-gallery-container rl-loading\" id=\"rl-gallery-container-1\" data-gallery_id=\"18101\"> <div class=\"rl-gallery rl-basicmasonry-gallery rl-hover-effect-2 rl-hover-icon-2\" id=\"rl-gallery-1\" data-gallery_no=\"1\"> <div class=\"rl-gutter-sizer\"><\/div><div class=\"rl-grid-sizer\"><\/div> <div class=\"rl-gallery-item rl-gallery-item-width-4\" > <div class=\"rl-gallery-item-content\"> <a href=\"https:\/\/www.stelvision.com\/astro\/wp-content\/uploads\/fv-contest\/c58\/2024-08-21-0327_4-U-IR-Sat_lapl3_ap1ASSTG2COLORSTELv2.jpg\" title=\"Occultation de Saturne (Pierre GILET)\" data-rl_title=\"Occultation de Saturne (Pierre GILET)\" class=\"rl-gallery-link\" data-rl_caption=\"La photo montre Saturne et la Lune quelques seconde avant l&apos;occultation | Date: 21.08.2024 | T\u00e9l\u00e9scope Newton OOUK VX12L (300\/1600) sur EQ6, cam\u00e9ra player one saturn M et saturn C, powermate x5, ADC ZWO, filtre IR pour la luminance et ir\/uv cut pour la couleur FD28 | Photo : Pierre GILET - Concours photo Stelvision\" data-rel=\"lightbox-gallery-1\"><img decoding=\"async\" src=\"https:\/\/www.stelvision.com\/astro\/wp-content\/uploads\/fv-contest\/c58\/2024-08-21-0327_4-U-IR-Sat_lapl3_ap1ASSTG2COLORSTELv2.jpg\" width=\"768\" height=\"768\" alt=\"Photo Occultation de Saturne\" \/><span class=\"rl-gallery-caption\"><span class=\"rl-gallery-item-title\">Occultation de Saturne (Pierre GILET)<\/span><\/span><\/a> <\/div> <\/div> <div class=\"rl-gallery-item\" > <div class=\"rl-gallery-item-content\"> <a href=\"https:\/\/www.stelvision.com\/astro\/wp-content\/uploads\/fv-contest\/c58\/2024-06-24-1700_5-U-Ha-Sun_Halpha_lapl2_ap3835_conv_aligned-copie.jpg\" title=\"Soleil Ha du 24\/06\/2024. (Florent LEONARCZYK)\" data-rl_title=\"Soleil Ha du 24\/06\/2024. (Florent LEONARCZYK)\" class=\"rl-gallery-link\" data-rl_caption=\"Protub\u00e9rance solaire d&apos;environ 150 000 km d&apos;altitude. La mati\u00e8re solaire retombant \u00e0 la surface nous d\u00e9voile un groupe de boulcles de champ magn\u00e9tique, c&apos;est se que l&apos;on app\u00e8le commun\u00e9ment une protub\u00e9rance. | Date: 24.6.2024 | Lunette Sky-Watcher 120 ED sur Monture AZ-EQ6 - Altair Triband D-ERF 130mm - Filtre \u00e9talon Daystar Quark Chromosphere - Interference Eliminator - QHY 5III 174 mono - vid\u00e9o de 60s + 60 flats - AS!4 : 30% - ImPPG + Astrosurface : d\u00e9convolution - Lusol3d : Mesure et cr\u00e9ation de la Terre \u00e0 l&apos;\u00e9chelle - Photoshop Colorisation et ajout de la Terre | Photo : Florent LEONARCZYK - Concours photo Stelvision\" data-rel=\"lightbox-gallery-1\"><img decoding=\"async\" src=\"https:\/\/www.stelvision.com\/astro\/wp-content\/uploads\/fv-contest\/c58\/2024-06-24-1700_5-U-Ha-Sun_Halpha_lapl2_ap3835_conv_aligned-copie.jpg\" width=\"768\" height=\"475\" alt=\"Photo Soleil Ha du 24\/06\/2024.\" \/><span class=\"rl-gallery-caption\"><span class=\"rl-gallery-item-title\">Soleil Ha du 24\/06\/2024. (Florent LEONARCZYK)<\/span><\/span><\/a> <\/div> <\/div> <div class=\"rl-gallery-item\" > <div class=\"rl-gallery-item-content\"> <a href=\"https:\/\/www.stelvision.com\/astro\/wp-content\/uploads\/fv-contest\/c58\/TSE-2024-sequence.jpg\" title=\"Chapelet de l\u2019\u00e9clipse totale de Soleil au Texas (Philippe Jacquot)\" data-rl_title=\"Chapelet de l\u2019\u00e9clipse totale de Soleil au Texas (Philippe Jacquot)\" class=\"rl-gallery-link\" data-rl_caption=\"Les derniers rayons du Soleil, avant et apr\u00e8s la totalit\u00e9, forment une succession de point lumineux que l&apos;on appelle les grains de Baily. Ce sont les crat\u00e8res de la Lune qui, sur son limbe, trahissent leurs pr\u00e9sences. Ils sont bien visibles sur la partie droite, en fin de totalit\u00e9, accompagn\u00e9s de magnifiques protub\u00e9rances. L&apos;arc rouge au bord du limbe lunaire est la chromosph\u00e8re du Soleil. L&apos;image centrale et une compilation de 6 photos \u00e0 diff\u00e9rents temps de pose (du 1\/2000s au 1\/2s) qui mont | Date: 8.4.2024 | Sony A7III, 600mm 6.3, 400 ISO, compilation de 6 images \u00e0 diff\u00e9rents temps de pose (du 1\/2000s au 1\/2s) pour le centre, 1\/2000s f 16 pour les autres (filtre solaire pour les phases partielles) | Photo : Philippe Jacquot - Concours photo Stelvision\" data-rel=\"lightbox-gallery-1\"><img decoding=\"async\" src=\"https:\/\/www.stelvision.com\/astro\/wp-content\/uploads\/fv-contest\/c58\/TSE-2024-sequence.jpg\" width=\"768\" height=\"512\" alt=\"Photo Chapelet de l&apos;\u00e9clipse totale de Soleil au Texas\" \/><span class=\"rl-gallery-caption\"><span class=\"rl-gallery-item-title\">Chapelet de l&rsquo;\u00e9clipse totale de Soleil au Texas (Philippe Jacquot)<\/span><\/span><\/a> <\/div> <\/div> <div class=\"rl-gallery-item\" > <div class=\"rl-gallery-item-content\"> <a href=\"https:\/\/www.stelvision.com\/astro\/wp-content\/uploads\/fv-contest\/c58\/2024-09-17-1932_1-iss_F05020-07661_lapl2_ap93_conv6.jpg\" title=\"Station Spatiale Internationale en couleur (Charline Giroud)\" data-rl_title=\"Station Spatiale Internationale en couleur (Charline Giroud)\" class=\"rl-gallery-link\" data-rl_caption=\"La photo a ete prise quelques jours apres le desamarrage de Boeing Starliner lors d&apos;un passage au zenith au dessus du Royaume-Uni en septembre 2024. | Date: 17.09.2024 | C11 edge HD sur EQ6R-Pro, filtre UV-IRcut, barlow x2 et ZWO662MC. Tracking realis\u00e9 en continu a 5600mm de focale via le logiciel SkyTrack. | Photo : Charline Giroud - Concours photo Stelvision\" data-rel=\"lightbox-gallery-1\"><img decoding=\"async\" src=\"https:\/\/www.stelvision.com\/astro\/wp-content\/uploads\/fv-contest\/c58\/2024-09-17-1932_1-iss_F05020-07661_lapl2_ap93_conv6.jpg\" width=\"768\" height=\"608\" alt=\"Photo Station Spatiale Internationale en couleur\" \/><span class=\"rl-gallery-caption\"><span class=\"rl-gallery-item-title\">Station Spatiale Internationale en couleur (Charline Giroud)<\/span><\/span><\/a> <\/div> <\/div> <div class=\"rl-gallery-item\" > <div class=\"rl-gallery-item-content\"> <a href=\"https:\/\/www.stelvision.com\/astro\/wp-content\/uploads\/fv-contest\/c55\/jupi-10-oct-middle-drot-2h-1.jpg\" title=\"Jupiter et sa GTR (Simon LABERGERE)\" data-rl_title=\"Jupiter et sa GTR (Simon LABERGERE)\" class=\"rl-gallery-link\" data-rl_caption=\"Jupiter et sa grosse tache rouge prise \u00e0 l&apos;observatoire du mont d&apos;arbois le 11 octobre 2023 | Date: 11.10.2023 | SC Meade 16&quot; - 662mc\/462mm - ADC PA MK3 - TV PM 2x | Photo : Simon LABERGERE - Concours photo Stelvision\" data-rel=\"lightbox-gallery-1\"><img decoding=\"async\" src=\"https:\/\/www.stelvision.com\/astro\/wp-content\/uploads\/fv-contest\/c55\/jupi-10-oct-middle-drot-2h-1.jpg\" width=\"768\" height=\"768\" alt=\"Photo Jupiter et sa GTR\" \/><span class=\"rl-gallery-caption\"><span class=\"rl-gallery-item-title\">Jupiter et sa GTR (Simon LABERGERE)<\/span><\/span><\/a> <\/div> <\/div> <div class=\"rl-gallery-item\" > <div class=\"rl-gallery-item-content\"> <a href=\"https:\/\/www.stelvision.com\/astro\/wp-content\/uploads\/fv-contest\/c55\/2023-11-09-0953_0TEST_lapl5_ap21ASGASGNClLSTEL.jpg\" title=\"Occultation de V\u00e9nus (Pierre GILET)\" data-rl_title=\"Occultation de V\u00e9nus (Pierre GILET)\" class=\"rl-gallery-link\" data-rl_caption=\"La photo montre V\u00e9nus 3 minutes avant son occultation par la lune | Date: 9.11.2023 | Newton Orion Optics UK N300\/1600 sur EQ6 pro, Cam\u00e9ras player one saturn M, televue barlow x3, adc ZWO, filtre IRpass 685 Baader, et U 320-380 baader, (v\u00e9nus) | Photo : Pierre GILET - Concours photo Stelvision\" data-rel=\"lightbox-gallery-1\"><img decoding=\"async\" src=\"https:\/\/www.stelvision.com\/astro\/wp-content\/uploads\/fv-contest\/c55\/2023-11-09-0953_0TEST_lapl5_ap21ASGASGNClLSTEL.jpg\" width=\"768\" height=\"768\" alt=\"Photo Occultation de V\u00e9nus\" \/><span class=\"rl-gallery-caption\"><span class=\"rl-gallery-item-title\">Occultation de V\u00e9nus (Pierre GILET)<\/span><\/span><\/a> <\/div> <\/div> <div class=\"rl-gallery-item\" > <div class=\"rl-gallery-item-content\"> <a href=\"https:\/\/www.stelvision.com\/astro\/wp-content\/uploads\/fv-contest\/c55\/2023-11-09-0945_1_V3_lapl5_ap38_conv_rawWD4.jpg\" title=\"Occultation de Venus par la Lune (Charline Giroud)\" data-rl_title=\"Occultation de Venus par la Lune (Charline Giroud)\" class=\"rl-gallery-link\" data-rl_caption=\"Venus, une minute avant de disparaitre derriere la Lune lors de l&apos;occultation du 9 novembre 2023 | Date: 9.11.2023 | CPC800 avec reducteur de focal, ASI294MC, traitement autostakkert, astrosurface, PS | Photo : Charline Giroud - Concours photo Stelvision\" data-rel=\"lightbox-gallery-1\"><img decoding=\"async\" src=\"https:\/\/www.stelvision.com\/astro\/wp-content\/uploads\/fv-contest\/c55\/2023-11-09-0945_1_V3_lapl5_ap38_conv_rawWD4.jpg\" width=\"768\" height=\"627\" alt=\"Photo Occultation de Venus par la Lune\" \/><span class=\"rl-gallery-caption\"><span class=\"rl-gallery-item-title\">Occultation de Venus par la Lune (Charline Giroud)<\/span><\/span><\/a> <\/div> <\/div> <div class=\"rl-gallery-item\" > <div class=\"rl-gallery-item-content\"> <a href=\"https:\/\/www.stelvision.com\/astro\/wp-content\/uploads\/fv-contest\/c55\/uranus-28-novembre-color.jpg\" title=\"Uranus et ses satellites (Stephane Gonzales)\" data-rl_title=\"Uranus et ses satellites (Stephane Gonzales)\" class=\"rl-gallery-link\" data-rl_caption=\"Uranus et de ses satellites en couleur a \u00e9t\u00e9 r\u00e9alis\u00e9e dans des conditions exceptionnelles. | Date: 28.11.2023 | T\u00e9lescope newton OO F4 Powermate 5x Player One Uranus (IMX585 c),Ircut pour la couleur ,60ms, 15mn pose totale | Photo : Stephane Gonzales - Concours photo Stelvision\" data-rel=\"lightbox-gallery-1\"><img decoding=\"async\" src=\"https:\/\/www.stelvision.com\/astro\/wp-content\/uploads\/fv-contest\/c55\/uranus-28-novembre-color.jpg\" width=\"768\" height=\"768\" alt=\"Photo Uranus et ses satellites\" \/><span class=\"rl-gallery-caption\"><span class=\"rl-gallery-item-title\">Uranus et ses satellites (Stephane Gonzales)<\/span><\/span><\/a> <\/div> <\/div> <div class=\"rl-gallery-item\" > <div class=\"rl-gallery-item-content\"> <a href=\"https:\/\/www.stelvision.com\/astro\/wp-content\/uploads\/fv-contest\/c55\/2024-02-11_201652_DSC_0708_final_small.jpg\" title=\"Lumi\u00e8re cendr\u00e9e (Gwenael BLANCK)\" data-rl_title=\"Lumi\u00e8re cendr\u00e9e (Gwenael BLANCK)\" class=\"rl-gallery-link\" data-rl_caption=\"La lumi\u00e8re cendr\u00e9e est due \u00e0 la faible illumination de la partie non \u00e9clair\u00e9e de la Lune par les nuages et oc\u00e9ans terrestres qui refl\u00e8tent la lumi\u00e8re du soleil. C&apos;est donc le reflet d&apos;un reflet. Il faut s&apos;imaginer sur la Lune \u00e0 ce moment - le clair de Terre serait \u00e9blouissant et magnifique! Depuis la Terre le spectacle est sublime aux jumelles ou (encore mieux) avec une lunette astronomique ou un t\u00e9lescope \u00e0 faible grossissement. | Date: 11.2.2024 | Nikon Z7 et objectif Nikkor Z 180-600. Photo prise \u00e0 600mm, ISO800, f6.3 et 5 secondes de pose. Suivi assur\u00e9 par une monture Skywatcher AZ-GTI (indispensable avec un tel temps de pose!) | Photo : Gwenael BLANCK - Concours photo Stelvision\" data-rel=\"lightbox-gallery-1\"><img decoding=\"async\" src=\"https:\/\/www.stelvision.com\/astro\/wp-content\/uploads\/fv-contest\/c55\/2024-02-11_201652_DSC_0708_final_small.jpg\" width=\"768\" height=\"1152\" alt=\"Photo Lumi\u00e8re cendr\u00e9e\" \/><span class=\"rl-gallery-caption\"><span class=\"rl-gallery-item-title\">Lumi\u00e8re cendr\u00e9e (Gwenael BLANCK)<\/span><\/span><\/a> <\/div> <\/div> <div class=\"rl-gallery-item\" > <div class=\"rl-gallery-item-content\"> <a href=\"https:\/\/www.stelvision.com\/astro\/wp-content\/uploads\/fv-contest\/c52\/TSE-2023-Jacquot.jpg\" title=\"Eclipse totale de Soleil \u00e0 Exmouth (Philippe JACQUOT)\" data-rl_title=\"Eclipse totale de Soleil \u00e0 Exmouth (Philippe JACQUOT)\" class=\"rl-gallery-link\" data-rl_caption=\"Cette \u00e9clipse \u00e9tait la premi\u00e8re hybride que j&apos;observais ce 20 avril 2023, un type d&apos;\u00e9clipse tr\u00e8s rare. Du fait de la rotondit\u00e9 de la Terre et suivant l&apos;endroit d&apos;o\u00f9 elle \u00e9tait observ\u00e9e, l&apos;\u00e9clipse \u00e9tait soit annulaire (la Lune ne couvrant pas enti\u00e8rement le Soleil), soit totale. Apr\u00e8s son passage dans l&apos;oc\u00e9an Indien, la trajectoire de l&apos;\u00e9clipse touchait la terre ferme sur la p\u00e9ninsule d&apos;Exmouth en Australie occidentale. Elle \u00e9tait alors totale mais courte (58 secondes sur mon lieu d&apos;obse | Date: 10.4.2023 | Compilation de 6 images \u00e0 diff\u00e9rents temps de pose (du 1\/2000s au 1\/2s). Sony A7III + objectif Sony 600 f\/d 16. | Photo : Philippe JACQUOT - Concours photo Stelvision\" data-rel=\"lightbox-gallery-1\"><img decoding=\"async\" src=\"https:\/\/www.stelvision.com\/astro\/wp-content\/uploads\/fv-contest\/c52\/TSE-2023-Jacquot.jpg\" width=\"768\" height=\"512\" alt=\"Photo Eclipse totale de Soleil \u00e0 Exmouth\" \/><span class=\"rl-gallery-caption\"><span class=\"rl-gallery-item-title\">Eclipse totale de Soleil \u00e0 Exmouth (Philippe JACQUOT)<\/span><\/span><\/a> <\/div> <\/div> <\/div> <\/div><\/p>\n\n\n\t\t\t<div style=\"color: grey; font-size: 0.8em; text-align: center;\">La suite apr\u00e8s cette annonce<\/div>\t\t\t<div class=\"boxFocus\" style=\"padding-bottom: 8px; margin-bottom: 12px; border-radius: 0; border: 1px solid #ddd;\">\t\t\t\t<a rel=\"nofollow\" href=\"https:\/\/www.stelvision.com\/astro\/boutique\/le-ciel-au-telescope\/?ref=middle\">\r\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.stelvision.com\/astro\/wp-content\/uploads\/2025\/10\/Ciel-au-telescope-1200x900-1.webp\" alt=\"visuel publicitaire livre le Ciel au t\u00e9lescope\" class=\"img-responsive\">\r\n\t\t\t\t<\/a>\r\n\t\t\t\t<p style=\"text-align: center; margin-bottom: 0em; margin-top: 0.25em;\"><strong><a rel=\"nofollow\" href=\"https:\/\/www.stelvision.com\/astro\/boutique\/le-ciel-au-telescope\/?ref=middle\">Le Ciel au t\u00e9lescope, le guide indispensable pour r\u00e9ussir vos observations<\/a><\/strong><\/p>\r\n\t\t\t<\/div>\n\n\n\n<p style=\"text-align:right\"><p style=\"text-align:right\" id=\"cat-cp\">cat\u00e9gories : <a href=\"#cat-ss\">Syst\u00e8me solaire<\/a> | <strong>Ciel profond<\/strong> | <a href=\"#cat-amb\">Ambiance <\/a>| <\/p>\n\n\n\n<hr class=\"wp-block-separator has-css-opacity\"\/>\n\n\n\n<h2 class=\"wp-block-heading\">Galerie Ciel profond<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><div class=\"rl-gallery-container rl-loading\" id=\"rl-gallery-container-2\" data-gallery_id=\"18102\"> <div class=\"rl-gallery rl-basicmasonry-gallery rl-hover-effect-2 rl-hover-icon-2\" id=\"rl-gallery-2\" data-gallery_no=\"2\"> <div class=\"rl-gutter-sizer\"><\/div><div class=\"rl-grid-sizer\"><\/div> <div class=\"rl-gallery-item rl-gallery-item-width-4\" > <div class=\"rl-gallery-item-content\"> <a href=\"https:\/\/www.stelvision.com\/astro\/wp-content\/uploads\/fv-contest\/c59\/WR134_HD.jpg\" title=\"Wolf-Rayet 134 (Emmanuel Joly)\" data-rl_title=\"Wolf-Rayet 134 (Emmanuel Joly)\" class=\"rl-gallery-link\" data-rl_caption=\"WR 134 est une \u00e9toile entour\u00e9e d&apos;une n\u00e9buleuse bleue form\u00e9e par des gaz ionis\u00e9s et de la poussi\u00e8re due \u00e0 ses vents stellaires. | Date: 3.7.2024 | T\u00e9lescope Sky-Watcher 200mm, F\/D=5, monture EQ6-R Pro, Cam\u00e9ra ASI 1600mm Pro, Filtres Antlia RVB et Ha &amp; OIII 3nm, pose totale 34h45 | Photo : Emmanuel Joly - Concours photo Stelvision\" data-rel=\"lightbox-gallery-2\"><img decoding=\"async\" src=\"https:\/\/www.stelvision.com\/astro\/wp-content\/uploads\/fv-contest\/c59\/WR134_HD.jpg\" width=\"768\" height=\"1047\" alt=\"Photo Wolf-Rayet 134\" \/><span class=\"rl-gallery-caption\"><span class=\"rl-gallery-item-title\">Wolf-Rayet 134 (Emmanuel Joly)<\/span><\/span><\/a> <\/div> <\/div> <div class=\"rl-gallery-item\" > <div class=\"rl-gallery-item-content\"> <a href=\"https:\/\/www.stelvision.com\/astro\/wp-content\/uploads\/fv-contest\/c59\/cephee-region.jpg\" title=\"Partie de chasse cosmique dans C\u00e9ph\u00e9e (GOZE S\u00e9bastien)\" data-rl_title=\"Partie de chasse cosmique dans C\u00e9ph\u00e9e (GOZE S\u00e9bastien)\" class=\"rl-gallery-link\" data-rl_caption=\"Une partie riche en poussi\u00e8res et n\u00e9buleuses dans la constellation de C\u00e9ph\u00e9e. La n\u00e9buleuse du requin au centre semble faire fuire ses proies :-) | Date: 5.4.2024 | Canon 6D et lunette FRA400 avec r\u00e9ducteur. 6H de pose environ au total compl\u00e9t\u00e9 par du Ha \u00e0 la ccd pour les zones concern\u00e9es. | Photo : GOZE S\u00e9bastien - Concours photo Stelvision\" data-rel=\"lightbox-gallery-2\"><img decoding=\"async\" src=\"https:\/\/www.stelvision.com\/astro\/wp-content\/uploads\/fv-contest\/c59\/cephee-region.jpg\" width=\"768\" height=\"501\" alt=\"Photo Partie de chasse cosmique dans C\u00e9ph\u00e9e\" \/><span class=\"rl-gallery-caption\"><span class=\"rl-gallery-item-title\">Partie de chasse cosmique dans C\u00e9ph\u00e9e (GOZE S\u00e9bastien)<\/span><\/span><\/a> <\/div> <\/div> <div class=\"rl-gallery-item\" > <div class=\"rl-gallery-item-content\"> <a href=\"https:\/\/www.stelvision.com\/astro\/wp-content\/uploads\/fv-contest\/Mesiier31_taille.jpeg\" title=\"Mesiier31_taille\" data-rl_title=\"Mesiier31_taille\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-2\"><img decoding=\"async\" src=\"https:\/\/www.stelvision.com\/astro\/wp-content\/uploads\/fv-contest\/Mesiier31_taille.jpeg\" width=\"768\" height=\"507\" alt=\"\" \/><span class=\"rl-gallery-caption\"><span class=\"rl-gallery-item-title\">Mesiier31_taille<\/span><\/span><\/a> <\/div> <\/div> <div class=\"rl-gallery-item\" > <div class=\"rl-gallery-item-content\"> <a href=\"https:\/\/www.stelvision.com\/astro\/wp-content\/uploads\/fv-contest\/c59\/M31-sign.jpg\" title=\"M31, notre voisine (Eric Brotons)\" data-rl_title=\"M31, notre voisine (Eric Brotons)\" class=\"rl-gallery-link\" data-rl_caption=\"La galaxie d&apos;Androm\u00e8de, \u00e9galement d\u00e9sign\u00e9e M31 dans le Catalogue de Messier et NGC 224, est une galaxie spirale situ\u00e9e \u00e0 environ 2,55 millions d&apos;ann\u00e9es-lumi\u00e8re du Soleil, dans la constellation d&apos;Androm\u00e8de. | Date: 28.09.2024 | T\u00e9l\u00e9objectif Samyang 135 mm F2.8 - EQ6-R pro - Autoguidage: ASI 120mm mono - Cam\u00e9ra : Altaire 533 c proTEC Gain : 220 T\u00b0 : - 5\u00b0 Filtre : - IDAS LPS - D3 - 233 poses de 90 sec - Int\u00e9gration : 5h50 min - Ciel bortle 8 | Photo : Eric Brotons - Concours photo Stelvision\" data-rel=\"lightbox-gallery-2\"><img decoding=\"async\" src=\"https:\/\/www.stelvision.com\/astro\/wp-content\/uploads\/fv-contest\/c59\/M31-sign.jpg\" width=\"768\" height=\"779\" alt=\"Photo M31, notre voisine\" \/><span class=\"rl-gallery-caption\"><span class=\"rl-gallery-item-title\">M31, notre voisine (Eric Brotons)<\/span><\/span><\/a> <\/div> <\/div> <div class=\"rl-gallery-item\" > <div class=\"rl-gallery-item-content\"> <a href=\"https:\/\/www.stelvision.com\/astro\/wp-content\/uploads\/fv-contest\/c56\/masterLight_BIN-1_9576x6388_EXPOSURE-600.00s_FILTER-L-QEF_RGB-etalonnee-G2V-2-LRGB-max-color-HD-1.jpg\" title=\"Plong\u00e9e dans le Tourbillon (Christophe de la Chapelle)\" data-rl_title=\"Plong\u00e9e dans le Tourbillon (Christophe de la Chapelle)\" class=\"rl-gallery-link\" data-rl_caption=\"M51 - Galaxie du Tourbillon. | Date: 6.3.2024 | 15x600s le 6-7 mars et 13*600s le 7-8 mars - ZWO ASI6200mc pro + Optolong L-QEF + CC Wynne Riccardi 3P + Newton\/Cassegrain Skyvision NC300\/1080 sur EQ8pro depuis la France M\u00e9tropolitaine. | Photo : Christophe de la Chapelle - Concours photo Stelvision\" data-rel=\"lightbox-gallery-2\"><img decoding=\"async\" src=\"https:\/\/www.stelvision.com\/astro\/wp-content\/uploads\/fv-contest\/c56\/masterLight_BIN-1_9576x6388_EXPOSURE-600.00s_FILTER-L-QEF_RGB-etalonnee-G2V-2-LRGB-max-color-HD-1.jpg\" width=\"768\" height=\"432\" alt=\"Photo Plong\u00e9e dans le Tourbillon\" \/><span class=\"rl-gallery-caption\"><span class=\"rl-gallery-item-title\">Plong\u00e9e dans le Tourbillon (Christophe de la Chapelle)<\/span><\/span><\/a> <\/div> <\/div> <div class=\"rl-gallery-item\" > <div class=\"rl-gallery-item-content\"> <a href=\"https:\/\/www.stelvision.com\/astro\/wp-content\/uploads\/fv-contest\/c56\/SH2-240_Spaghetti.jpg\" title=\"Les Spaghettis (Christophe HERDEWN)\" data-rl_title=\"Les Spaghettis (Christophe HERDEWN)\" class=\"rl-gallery-link\" data-rl_caption=\"La n\u00e9buleuse du Spaghetti (SH2-240). Bon app\u00e9tit. Cette n\u00e9buleuse est un r\u00e9manent de supernova situ\u00e9 dans la constellation du taureau. \u00c2g\u00e9 d&apos;environ 40000 ans, il se situe \u00e0 environ 3000 ann\u00e9es lumi\u00e8res. Ce r\u00e9manent de supernova est associ\u00e9 \u00e0 un pulsar que l\u2019on ne voit pas. Cette n\u00e9buleuse est situ\u00e9e \u00e0 approximativement entre 1 000 et 3 000 ann\u00e9es-lumi\u00e8re de la Terre en direction des constellations du Taureau et du Cocher. Elle compos\u00e9e essentiellement de Ha et de OIII. | Date: 16.12.2023 | 105 photos brutes de 500s + DOF. Je n\u2019ai retenu que 92 photos en mettant un taux de rejet \u00e0 88%, pour avoir le meilleur taux FWHM. Au total 12h3\/4. Monture Zwo AM5 + boitiier Asiair Plus Lunette Askar FRA400 avec r\u00e9ducteur (focale 280mm) \u2013 Cam\u00e9ra Zwo Asi2400 FF \u2013 Filtre L-Utimate Pr\u00e9traitement manuel sous Siril. Traitement Lightroom et Photoshop. | Photo : Christophe HERDEWN - Concours photo Stelvision\" data-rel=\"lightbox-gallery-2\"><img decoding=\"async\" src=\"https:\/\/www.stelvision.com\/astro\/wp-content\/uploads\/fv-contest\/c56\/SH2-240_Spaghetti.jpg\" width=\"768\" height=\"536\" alt=\"Photo Les Spaghettis\" \/><span class=\"rl-gallery-caption\"><span class=\"rl-gallery-item-title\">Les Spaghettis (Christophe HERDEWN)<\/span><\/span><\/a> <\/div> <\/div> <div class=\"rl-gallery-item\" > <div class=\"rl-gallery-item-content\"> <a href=\"https:\/\/www.stelvision.com\/astro\/wp-content\/uploads\/fv-contest\/c56\/Orion-135-Pano-s3.jpg\" title=\"Le complexe d\u2019Orion au grand champ (Louis LEROUX-GERE)\" data-rl_title=\"Le complexe d\u2019Orion au grand champ (Louis LEROUX-GERE)\" class=\"rl-gallery-link\" data-rl_caption=\"La constellation d\u2019Orion est sans aucun doute la partie la plus spectaculaire de notre ciel d\u2019hiver dans l&apos;h\u00e9misph\u00e8re Nord. Cette zone est incroyablement dense en gaz et en n\u00e9buleuses. J\u2019ai voulu y consacrer un peu de temps durant les quelques heures de beau temps ces derniers jours. Je n\u2019ai pu y mettre que 2h car j\u2019avais un autre setup qui tournait \u00e0 c\u00f4t\u00e9 pour un autre projet (FACT), mais je suis incroyablement surpris par le combo 135\/EOS R ! | Date: 9.1.2024 | -Canon EOS R modded by a-m.de -Samyang 135mm f\/2 ED UMC -Sky Watcher Star Adventurer GTi -2 tuiles de 60*60s 1250ISO f\/2.4 -Pix &amp; PS -Bortle 4 SQM 21.1 | Photo : Louis LEROUX-GERE - Concours photo Stelvision\" data-rel=\"lightbox-gallery-2\"><img decoding=\"async\" src=\"https:\/\/www.stelvision.com\/astro\/wp-content\/uploads\/fv-contest\/c56\/Orion-135-Pano-s3.jpg\" width=\"768\" height=\"960\" alt=\"Photo Le complexe d\u2019Orion au grand champ\" \/><span class=\"rl-gallery-caption\"><span class=\"rl-gallery-item-title\">Le complexe d\u2019Orion au grand champ (Louis LEROUX-GERE)<\/span><\/span><\/a> <\/div> <\/div> <div class=\"rl-gallery-item\" > <div class=\"rl-gallery-item-content\"> <a href=\"https:\/\/www.stelvision.com\/astro\/wp-content\/uploads\/fv-contest\/c56\/abell-6-web.jpg\" title=\"Abell 6 \u2013 HFG1 (Northern France Remote)\" data-rl_title=\"Abell 6 \u2013 HFG1 (Northern France Remote)\" class=\"rl-gallery-link\" data-rl_caption=\"Voici la seconde image de notre team Northern France Remote : Nous sommes ravis de vous pr\u00e9senter notre version d&apos;Abell 6 et HFG1, une cible tr\u00e8s faible qui, m\u00eame sous le ciel exceptionnel Espagnol aura demand\u00e9 pr\u00e8s de 90h de pose. Deux n\u00e9buleuses plan\u00e9taires, donc des \u00e9toiles en fin de vie qui expulsent leur gaz, elles sont particuli\u00e8rement esth\u00e9tiques : HFG1, la n\u00e9buleuse la plus importante pr\u00e9sente une structure en arc de cercle, on y voit m\u00eame une galaxie en arri\u00e8re plan ! La seconde n\u00e9bule | Date: 1.12.2023 | Askar 107PHQ \/ Monture Eq6rpro, Asi2600MM, filtre Antlia HORVB 45h de H \/ 40h de O \/3h de RVB | Photo : Northern France Remote - Concours photo Stelvision\" data-rel=\"lightbox-gallery-2\"><img decoding=\"async\" src=\"https:\/\/www.stelvision.com\/astro\/wp-content\/uploads\/fv-contest\/c56\/abell-6-web.jpg\" width=\"768\" height=\"512\" alt=\"Photo Abell 6 - HFG1\" \/><span class=\"rl-gallery-caption\"><span class=\"rl-gallery-item-title\">Abell 6 &#8211; HFG1 (Northern France Remote)<\/span><\/span><\/a> <\/div> <\/div> <div class=\"rl-gallery-item\" > <div class=\"rl-gallery-item-content\"> <a href=\"https:\/\/www.stelvision.com\/astro\/wp-content\/uploads\/fv-contest\/c56\/M33_L-RHVOBO_publication-web.jpg\" title=\"M33 (Northern France Remote)\" data-rl_title=\"M33 (Northern France Remote)\" class=\"rl-gallery-link\" data-rl_caption=\"Prise sous les cieux espagnols, c&apos;est un grand classique du ciel d&apos;automne, il s&apos;agit de la galaxie du triangle ou M33 Plusieurs dizaines d&apos;heures de poses ont \u00e9t\u00e9 cumul\u00e9es pour r\u00e9aliser cette vue : 18 heures de luminance auquel s&apos;ajoute 12 heures de RVB et 18 heures de H alpha et 12h d&apos;Oxyg\u00e8ne. Le ha permet de r\u00e9v\u00e9ler les nuages de gaz qui se trouvent dans les bras de la galaxie Les 700mm de focale de la lunette permettent de d\u00e9tailler le fourmillement d&apos;\u00e9toiles de la galaxie. Dans le fo | Date: 15.11.2023 | Askar 107PHQ \/ Asi2600MM \/ Monture EQ6r | Photo : Northern France Remote - Concours photo Stelvision\" data-rel=\"lightbox-gallery-2\"><img decoding=\"async\" src=\"https:\/\/www.stelvision.com\/astro\/wp-content\/uploads\/fv-contest\/c56\/M33_L-RHVOBO_publication-web.jpg\" width=\"768\" height=\"500\" alt=\"Photo M33\" \/><span class=\"rl-gallery-caption\"><span class=\"rl-gallery-item-title\">M33 (Northern France Remote)<\/span><\/span><\/a> <\/div> <\/div> <div class=\"rl-gallery-item\" > <div class=\"rl-gallery-item-content\"> <a href=\"https:\/\/www.stelvision.com\/astro\/wp-content\/uploads\/fv-contest\/Final-2.png\" title=\"N\u00e9buleuse de la bulle (Charline Giroud)\" data-rl_title=\"N\u00e9buleuse de la bulle (Charline Giroud)\" class=\"rl-gallery-link\" data-rl_caption=\"Photo prise depuis l&apos;Angleterre, un des rares soirs d&apos;\u00e9t\u00e9 ou le ciel \u00e9tait clair | Date : 19.08.2023 | C11EHD, ASI294MC, filtre duo band. Traitements PixInsight | Photo : Charline Giroud - Concours photo Stelvision\" data-rel=\"lightbox-gallery-2\"><img decoding=\"async\" src=\"https:\/\/www.stelvision.com\/astro\/wp-content\/uploads\/fv-contest\/Final-2.png\" width=\"768\" height=\"768\" alt=\"Photo N\u00e9buleuse de la bulle\" \/><span class=\"rl-gallery-caption\"><span class=\"rl-gallery-item-title\">N\u00e9buleuse de la bulle (Charline Giroud)<\/span><\/span><\/a> <\/div> <\/div> <div class=\"rl-gallery-item\" > <div class=\"rl-gallery-item-content\"> <a href=\"https:\/\/www.stelvision.com\/astro\/wp-content\/uploads\/fv-contest\/c53\/M31-Ha-ircut-10-09-23.jpg\" title=\"M31 androm\u00e8de (Art89300)\" data-rl_title=\"M31 androm\u00e8de (Art89300)\" class=\"rl-gallery-link\" data-rl_caption=\"M31 prise en Ha-rvb | Date: 10.09.2023 | lunette sw72ed avec reducteur 0.85, asi2600mc, ircut de la camera (8h), filtre optolong Lextreme (3h), monture eq6r, asiair plus, pose unitaire de 300secs gain 100. | Photo : Art89300 - Concours photo Stelvision\" data-rel=\"lightbox-gallery-2\"><img decoding=\"async\" src=\"https:\/\/www.stelvision.com\/astro\/wp-content\/uploads\/fv-contest\/c53\/M31-Ha-ircut-10-09-23.jpg\" width=\"768\" height=\"468\" alt=\"Photo M31 androm\u00e8de\" \/><span class=\"rl-gallery-caption\"><span class=\"rl-gallery-item-title\">M31 androm\u00e8de (Art89300)<\/span><\/span><\/a> <\/div> <\/div> <div class=\"rl-gallery-item\" > <div class=\"rl-gallery-item-content\"> <a href=\"https:\/\/www.stelvision.com\/astro\/wp-content\/uploads\/fv-contest\/c53\/SH2-99-SH2-100-1500pix.jpg\" title=\"Champ sur Sh2-99 et Sh2-100 (Jordan Marli\u00e8re)\" data-rl_title=\"Champ sur Sh2-99 et Sh2-100 (Jordan Marli\u00e8re)\" class=\"rl-gallery-link\" data-rl_caption=\"Tr\u00e8s heureux de partager avec vous cette photographie qui est \u00e0 ce jour, celle o\u00f9 j\u2019ai r\u00e9alis\u00e9 le plus de temps de pose : 37H30. R\u00e9alis\u00e9 entre le 29 mai et le 15 juin 2023. Il s\u2019agit d\u2019un assemblage colorim\u00e9trique, avec les couches SII, Ha, OIII, et RGB. SH2-99 et SH2-100 sont des n\u00e9buleuses en \u00e9mission visibles dans la constellation du cygne, au bord d&apos;un tron\u00e7on tr\u00e8s lumineux de la Voie lact\u00e9e. Ces petites r\u00e9gions d\u2019hydrog\u00e8ne ionis\u00e9 sont situ\u00e9es respectivement \u00e0 une distance d\u2019environ, 26000 | Date: 15.6.2023 | S : 31x600s - H : 85 x 600s - O : 73 x 600s R : 110 x 60s - G : 110 x 60s - B : 140 x 60s Sharpstar Optics Askar FRA600 avec r\u00e9ducteur 0,7x ZWO ASI Cameras ASI1600 Pro mono Antlia Astronomy Filter 3nm SII, Ha et OIII \u2013 Filtres Zwo R, G, et B Sky-Watcher AZ Eq6 GT Primalucelab EAGLE 4 \u2013 Sesto Senso II \u2013 ECCO2 | Photo : Jordan Marli\u00e8re - Concours photo Stelvision\" data-rel=\"lightbox-gallery-2\"><img decoding=\"async\" src=\"https:\/\/www.stelvision.com\/astro\/wp-content\/uploads\/fv-contest\/c53\/SH2-99-SH2-100-1500pix.jpg\" width=\"768\" height=\"530\" alt=\"Photo Champ sur Sh2-99 et Sh2-100\" \/><span class=\"rl-gallery-caption\"><span class=\"rl-gallery-item-title\">Champ sur Sh2-99 et Sh2-100 (Jordan Marli\u00e8re)<\/span><\/span><\/a> <\/div> <\/div> <div class=\"rl-gallery-item\" > <div class=\"rl-gallery-item-content\"> <a href=\"https:\/\/www.stelvision.com\/astro\/wp-content\/uploads\/fv-contest\/c53\/M51_Finale_6_crop-17-04-23-Q268.jpg\" title=\"M51 \u2013 Galaxie du Tourbillon (Thierry Holer)\" data-rl_title=\"M51 \u2013 Galaxie du Tourbillon (Thierry Holer)\" class=\"rl-gallery-link\" data-rl_caption=\"M51 ou galaxie du Tourbillon est une galaxie spirale situ\u00e9e dans la constellation des Chiens de chasse. En compagnie de NGC 5195, quelquefois d\u00e9sign\u00e9e comme M51B, M51 forme un couple de galaxies en interaction. Elle a \u00e9t\u00e9 d\u00e9couverte par l&apos;astronome fran\u00e7ais Charles Messier en 1773. | Date: 17.4.2023 | Tube EdgeHD 11&quot; sur monture AZ-EQ6 - Cam\u00e9ra QHY268 M. Filtres Antlia 3nm H-alpha et 36 mm RVB - Antlia Luminance Pro. Logiciels PHD2 et NINA. Traitement PixInsight \u00b7 | Photo : Thierry Holer - Concours photo Stelvision\" data-rel=\"lightbox-gallery-2\"><img decoding=\"async\" src=\"https:\/\/www.stelvision.com\/astro\/wp-content\/uploads\/fv-contest\/c53\/M51_Finale_6_crop-17-04-23-Q268.jpg\" width=\"768\" height=\"558\" alt=\"Photo M51 - Galaxie du Tourbillon\" \/><span class=\"rl-gallery-caption\"><span class=\"rl-gallery-item-title\">M51 &#8211; Galaxie du Tourbillon (Thierry Holer)<\/span><\/span><\/a> <\/div> <\/div> <div class=\"rl-gallery-item\" > <div class=\"rl-gallery-item-content\"> <a href=\"https:\/\/www.stelvision.com\/astro\/wp-content\/uploads\/fv-contest\/c53\/IC4592.jpg\" title=\"r\u00e9gion de rho ophiuchi (mosa\u00efque de 9 tuiles) (manu69)\" data-rl_title=\"r\u00e9gion de rho ophiuchi (mosa\u00efque de 9 tuiles) (manu69)\" class=\"rl-gallery-link\" data-rl_caption=\"lors de mon voyage \u00e0 la palma cet \u00e9t\u00e9 j&apos;ai enfin r\u00e9alis\u00e9 mon r\u00eave qui \u00e9tait de r\u00e9aliser cette mosa\u00efque de 9 tuiles sur rho ophiuchi r\u00e9alis\u00e9e sur 7 nuits | Date: 16.8.2023 | Samyang 135 \u00e0 F\/D=2, monture star adventurer GTi, cam\u00e9ra ZWO ASI533MC Pro, filtre ZWO IR cut, 1h24 de pose par tuile donc 12h36 de temps de pose total | Photo : manu69 - Concours photo Stelvision\" data-rel=\"lightbox-gallery-2\"><img decoding=\"async\" src=\"https:\/\/www.stelvision.com\/astro\/wp-content\/uploads\/fv-contest\/c53\/IC4592.jpg\" width=\"768\" height=\"724\" alt=\"Photo r\u00e9gion de rho ophiuchi (mosa\u00efque de 9 tuiles)\" \/><span class=\"rl-gallery-caption\"><span class=\"rl-gallery-item-title\">r\u00e9gion de rho ophiuchi (mosa\u00efque de 9 tuiles) (manu69)<\/span><\/span><\/a> <\/div> <\/div> <div class=\"rl-gallery-item\" > <div class=\"rl-gallery-item-content\"> <a href=\"https:\/\/www.stelvision.com\/astro\/wp-content\/uploads\/fv-contest\/stel.jpg\" title=\"Un marvel dans les \u00e9toiles ! (Eric Brotons)\" data-rl_title=\"Un marvel dans les \u00e9toiles ! (Eric Brotons)\" class=\"rl-gallery-link\" data-rl_caption=\"La n\u00e9buleuse du Casque de Thor, NGC 2359, est une n\u00e9buleuse en \u00e9mission situ\u00e9e dans la constellation du Grand Chien \u00e0 environ 15 000 ann\u00e9es-lumi\u00e8re du syst\u00e8me solaire. | Date : 25.2.2023 | Technique : SW 150\/750 mm - EQ6-R Pro - Autoguidage: ASI 120mm mono - Prise de vue : cam\u00e9ra Altair 533 c Pro TEC Gain 220 T\u00b0- 5 Filtre \/ Idas NBZ - 37 poses de 8 min Temps de poses : 4h56 min - Ciel bortle 6 | Photo : Eric Brotons - Concours photo Stelvision\" data-rel=\"lightbox-gallery-2\"><img decoding=\"async\" src=\"https:\/\/www.stelvision.com\/astro\/wp-content\/uploads\/fv-contest\/stel-768x775.jpg\" width=\"768\" height=\"775\" alt=\"photo Un marvel dans les \u00e9toiles !\" \/><span class=\"rl-gallery-caption\"><span class=\"rl-gallery-item-title\">Un marvel dans les \u00e9toiles ! (Eric Brotons)<\/span><\/span><\/a> <\/div> <\/div> <\/div> <\/div> <\/p>\n\n\n\t\t\t<div style=\"color: grey; font-size: 0.8em; text-align: center;\">La suite apr\u00e8s cette annonce<\/div>\t\t\t<div class=\"boxFocus\" style=\"padding-bottom: 8px; margin-bottom: 12px; border-radius: 0; border: 1px solid #ddd;\">\t\t\t\t<a rel=\"nofollow\" href=\"https:\/\/www.stelvision.com\/astro\/boutique\/le-ciel-au-telescope\/?ref=middle\">\r\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.stelvision.com\/astro\/wp-content\/uploads\/2025\/10\/Ciel-au-telescope-1200x900-1.webp\" alt=\"visuel publicitaire livre le Ciel au t\u00e9lescope\" class=\"img-responsive\">\r\n\t\t\t\t<\/a>\r\n\t\t\t\t<p style=\"text-align: center; margin-bottom: 0em; margin-top: 0.25em;\"><strong><a rel=\"nofollow\" href=\"https:\/\/www.stelvision.com\/astro\/boutique\/le-ciel-au-telescope\/?ref=middle\">Le Ciel au t\u00e9lescope, le guide indispensable pour r\u00e9ussir vos observations<\/a><\/strong><\/p>\r\n\t\t\t<\/div>\n\n\n\n<p style=\"text-align:right\"><p style=\"text-align:right\" id=\"cat-amb\">cat\u00e9gories : <a href=\"#cat-ss\">Syst\u00e8me solaire<\/a> | <a href=\"#cat-cp\">Ciel profond<\/a> | <strong>Ambiance <\/strong><\/p>\n\n\n\n<hr class=\"wp-block-separator has-css-opacity\"\/>\n\n\n\n<h2 class=\"wp-block-heading\">Galerie Ambiance<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"> <div class=\"rl-gallery-container rl-loading\" id=\"rl-gallery-container-3\" data-gallery_id=\"17982\"> <div class=\"rl-gallery rl-basicmasonry-gallery rl-hover-effect-2 rl-hover-icon-2\" id=\"rl-gallery-3\" data-gallery_no=\"3\"> <div class=\"rl-gutter-sizer\"><\/div><div class=\"rl-grid-sizer\"><\/div> <div class=\"rl-gallery-item rl-gallery-item-width-4\" > <div class=\"rl-gallery-item-content\"> <a href=\"https:\/\/www.stelvision.com\/astro\/wp-content\/uploads\/fv-contest\/c57\/Annecy-Aurores-VL.jpg\" title=\"L\u2019aurore et la Voie Lact\u00e9e (Philippe Jacquot)\" data-rl_title=\"L\u2019aurore et la Voie Lact\u00e9e (Philippe Jacquot)\" class=\"rl-gallery-link\" data-rl_caption=\"Ce samedi 11 mai 2024, une explosion solaire exceptionnelle produisait de magnifiques aurores bor\u00e9ales sur la France. La danse des draperies aurorales \u00e9taient bien visibles \u00e0 l&apos;\u0153il nu et l&apos;arche de la Voie Lact\u00e9e venait se fondre dans l&apos;aurore qui se terminait au centre, \u00e0 l&apos;aplomb du Mont-Blanc. | Date: 11.5.2024 | Panoramique de 16 images, Sony A7s d\u00e9filtr\u00e9, 14mm 1.8 ouvert \u00e0 2.8 pose 4s \u00e0 6400 ISO. | Photo : Philippe Jacquot - Concours photo Stelvision\" data-rel=\"lightbox-gallery-3\"><img decoding=\"async\" src=\"https:\/\/www.stelvision.com\/astro\/wp-content\/uploads\/fv-contest\/c57\/Annecy-Aurores-VL.jpg\" width=\"768\" height=\"384\" alt=\"Photo L&apos;aurore et la Voie Lact\u00e9e\" \/><span class=\"rl-gallery-caption\"><span class=\"rl-gallery-item-title\">L&rsquo;aurore et la Voie Lact\u00e9e (Philippe Jacquot)<\/span><\/span><\/a> <\/div> <\/div> <div class=\"rl-gallery-item\" > <div class=\"rl-gallery-item-content\"> <a href=\"https:\/\/www.stelvision.com\/astro\/wp-content\/uploads\/fv-contest\/c57\/GD-AURORE-11052024-IMG_8758.jpg\" title=\"Couleurs et reflets d\u2019aurores (Guillaume DELEZIR)\" data-rl_title=\"Couleurs et reflets d\u2019aurores (Guillaume DELEZIR)\" class=\"rl-gallery-link\" data-rl_caption=\"Photo prise \u00e0 l&apos;occasion de cette nuit d&apos;aurores bor\u00e9ales exceptionnelles du 10-11 mai 2024 en Bretagne | Date: 11.5.2024 | CANON 200D SIGMA 18-35 mm 18 mm f\/1,8 panorama de 4 tuiles pose de 2s ISO 3200 | Photo : Guillaume DELEZIR - Concours photo Stelvision\" data-rel=\"lightbox-gallery-3\"><img decoding=\"async\" src=\"https:\/\/www.stelvision.com\/astro\/wp-content\/uploads\/fv-contest\/c57\/GD-AURORE-11052024-IMG_8758.jpg\" width=\"768\" height=\"431\" alt=\"Photo Couleurs et reflets d&apos;aurores\" \/><span class=\"rl-gallery-caption\"><span class=\"rl-gallery-item-title\">Couleurs et reflets d&rsquo;aurores (Guillaume DELEZIR)<\/span><\/span><\/a> <\/div> <\/div> <div class=\"rl-gallery-item\" > <div class=\"rl-gallery-item-content\"> <a href=\"https:\/\/www.stelvision.com\/astro\/wp-content\/uploads\/fv-contest\/c57\/Ambiance-lac-Lauzon.jpg\" title=\"Ambiance Lac Lauzon (Dominique JOUBERT)\" data-rl_title=\"Ambiance Lac Lauzon (Dominique JOUBERT)\" class=\"rl-gallery-link\" data-rl_caption=\"Bivouac au Lac Lauzon. Ambiance particuli\u00e8re avec une brume qui allait et venat tout au long de la nuit. 4 heures \u00e0 guetter les \u00e9claircies pour pouvoir r\u00e9ussir cette photos | Date: 1.6.2024 | Canon R6 d\u00e9liltr\u00e9 \/ 35mm Sigma \/ Oanorama de 3x3 photos Sol : 30s \/ F2 \/ 4000 Iso Ciel : idem avec suivi par Benro Polaris \/ Assemblage autopano + Lightroom | Photo : Dominique JOUBERT - Concours photo Stelvision\" data-rel=\"lightbox-gallery-3\"><img decoding=\"async\" src=\"https:\/\/www.stelvision.com\/astro\/wp-content\/uploads\/fv-contest\/c57\/Ambiance-lac-Lauzon.jpg\" width=\"768\" height=\"522\" alt=\"Photo Ambiance Lac Lauzon\" \/><span class=\"rl-gallery-caption\"><span class=\"rl-gallery-item-title\">Ambiance Lac Lauzon (Dominique JOUBERT)<\/span><\/span><\/a> <\/div> <\/div> <div class=\"rl-gallery-item\" > <div class=\"rl-gallery-item-content\"> <a href=\"https:\/\/www.stelvision.com\/astro\/wp-content\/uploads\/fv-contest\/c57\/DSC07866.jpg\" title=\"La magie des aurores bor\u00e9ales (Sylvain Wallart)\" data-rl_title=\"La magie des aurores bor\u00e9ales (Sylvain Wallart)\" class=\"rl-gallery-link\" data-rl_caption=\"Cette nuit fut magique ! De magnifiques aurores bor\u00e9ales sont apparues pendant un long moment et les couleurs sont magnifiques ! Elles \u00e9taient parfaitement visibles \u00e0 l&apos;\u0153il nu et le ciel entier s&apos;est couvert d&apos;aurores ! Je ne pensais jamais voir \u00e7a depuis le nord de la France ! | Date: 10.05.2024 | Sony A7iii - 17mm F2.8 - 4sec - 2800 ISO | Photo : Sylvain Wallart - Concours photo Stelvision\" data-rel=\"lightbox-gallery-3\"><img decoding=\"async\" src=\"https:\/\/www.stelvision.com\/astro\/wp-content\/uploads\/fv-contest\/c57\/DSC07866.jpg\" width=\"768\" height=\"512\" alt=\"Photo La magie des aurores bor\u00e9ales\" \/><span class=\"rl-gallery-caption\"><span class=\"rl-gallery-item-title\">La magie des aurores bor\u00e9ales (Sylvain Wallart)<\/span><\/span><\/a> <\/div> <\/div> <div class=\"rl-gallery-item\" > <div class=\"rl-gallery-item-content\"> <a href=\"https:\/\/www.stelvision.com\/astro\/wp-content\/uploads\/fv-contest\/c57\/WEB_IMG_3845-duo-copie.jpg\" title=\"La qu\u00eate du diad\u00e8me (Marion Kabac)\" data-rl_title=\"La qu\u00eate du diad\u00e8me (Marion Kabac)\" class=\"rl-gallery-link\" data-rl_caption=\"\u00ab\u00a0La terre porte un diad\u00e8me de roses blanches, plus grandes que chaque rayon de soleil. D\u2019un bout \u00e0 l\u2019autre des p\u00f4les glac\u00e9s comme des diamants, un ruban brode tous nos souhaits comme l\u2019on se donne la main.\u00a0\u00bb Le panorama est compos\u00e9 de 27 photographies\u2026 ce n\u2019est pas le genre d\u2019exercice auquel je suis habitu\u00e9e ! Mais je m\u2019en sors plut\u00f4t bien cette fois. Ma plus grande interrogation \u00e9tait : comment r\u00e9aliser un vrai autoportrait au coeur de ce panorama, sans disparaitre dans l\u2019immensit\u00e9 de ses 300 | Date: 1.8.2024 | Canon 6d mark2 + Sigma 35mm f\/1.4 Art. Panorama de 27 poses uniques de 10 secondes \u00e0 f\/1.6 ISO 3200 | Photo : Marion Kabac - Concours photo Stelvision\" data-rel=\"lightbox-gallery-3\"><img decoding=\"async\" src=\"https:\/\/www.stelvision.com\/astro\/wp-content\/uploads\/fv-contest\/c57\/WEB_IMG_3845-duo-copie.jpg\" width=\"768\" height=\"614\" alt=\"Photo La qu\u00eate du diad\u00e8me\" \/><span class=\"rl-gallery-caption\"><span class=\"rl-gallery-item-title\">La qu\u00eate du diad\u00e8me (Marion Kabac)<\/span><\/span><\/a> <\/div> <\/div> <div class=\"rl-gallery-item\" > <div class=\"rl-gallery-item-content\"> <a href=\"https:\/\/www.stelvision.com\/astro\/wp-content\/uploads\/fv-contest\/c54\/Aurores-VF-5.jpg\" title=\"Aurora\u2019s bridge (Mickael Coulon)\" data-rl_title=\"Aurora\u2019s bridge (Mickael Coulon)\" class=\"rl-gallery-link\" data-rl_caption=\"La nuit du 5 au 6 f\u00e9vrier, un incroyable cadeau nous a \u00e9t\u00e9 fait, celui d&apos;une \u00e9ruption aurorale incroyable. Le ciel, couvert de nuages 30 minutes plus t\u00f4t se teint de vagues vertes et rouges impressionnantes ! Ici immortalis\u00e9e sur une pose de 6s on voit bien les deux nuances de couleurs. De nombreuses autres images ont \u00e9t\u00e9 prises au cours de cette nuit de folie ! | Date: 6.2.2024 | Canon 6d \/ TTArtisans 11mm \/ 6s de pose \/ 3200iso | Photo : Mickael Coulon - Concours photo Stelvision\" data-rel=\"lightbox-gallery-3\"><img decoding=\"async\" src=\"https:\/\/www.stelvision.com\/astro\/wp-content\/uploads\/fv-contest\/c54\/Aurores-VF-5.jpg\" width=\"768\" height=\"512\" alt=\"Photo Aurora&apos;s bridge\" \/><span class=\"rl-gallery-caption\"><span class=\"rl-gallery-item-title\">Aurora&rsquo;s bridge (Mickael Coulon)<\/span><\/span><\/a> <\/div> <\/div> <div class=\"rl-gallery-item\" > <div class=\"rl-gallery-item-content\"> <a href=\"https:\/\/www.stelvision.com\/astro\/wp-content\/uploads\/fv-contest\/c54\/Bilboquet-au-Mont-Aiguille.jpg\" title=\"Bilboquet au Mont Aiguille (Dominique Joubert)\" data-rl_title=\"Bilboquet au Mont Aiguille (Dominique Joubert)\" class=\"rl-gallery-link\" data-rl_caption=\"Coucher de la Pleine Lune dur le Mont Aiguille | Date: 1.10.2023 | Canon R7 499mm Canon extendeur 1,4 1\/100s 299 Iso F8 Pose unique | Photo : Dominique Joubert - Concours photo Stelvision\" data-rel=\"lightbox-gallery-3\"><img decoding=\"async\" src=\"https:\/\/www.stelvision.com\/astro\/wp-content\/uploads\/fv-contest\/c54\/Bilboquet-au-Mont-Aiguille.jpg\" width=\"768\" height=\"512\" alt=\"Photo Bilboquet au Mont Aiguille\" \/><span class=\"rl-gallery-caption\"><span class=\"rl-gallery-item-title\">Bilboquet au Mont Aiguille (Dominique Joubert)<\/span><\/span><\/a> <\/div> <\/div> <div class=\"rl-gallery-item\" > <div class=\"rl-gallery-item-content\"> <a href=\"https:\/\/www.stelvision.com\/astro\/wp-content\/uploads\/fv-contest\/c54\/Aurores-VF-2.jpg\" title=\"Aurora\u2019s House (Mickael Coulon)\" data-rl_title=\"Aurora\u2019s House (Mickael Coulon)\" class=\"rl-gallery-link\" data-rl_caption=\"Deux nuances aurorales sont pr\u00e9sentes sur cette image : une tr\u00e8s large aurore verte et un pilier rouge au centre de l&apos;image. La cabane au bord du lac habille joliment ce premier plan enneig\u00e9. | Date: 5.2.2024 | Canon 6d \/ TT Artisans 11mm \/ 13s de pose \/ F2.8 \/ 4000iso | Photo : Mickael Coulon - Concours photo Stelvision\" data-rel=\"lightbox-gallery-3\"><img decoding=\"async\" src=\"https:\/\/www.stelvision.com\/astro\/wp-content\/uploads\/fv-contest\/c54\/Aurores-VF-2.jpg\" width=\"768\" height=\"432\" alt=\"Photo Aurora&apos;s House\" \/><span class=\"rl-gallery-caption\"><span class=\"rl-gallery-item-title\">Aurora&rsquo;s House (Mickael Coulon)<\/span><\/span><\/a> <\/div> <\/div> <div class=\"rl-gallery-item\" > <div class=\"rl-gallery-item-content\"> <a href=\"https:\/\/www.stelvision.com\/astro\/wp-content\/uploads\/fv-contest\/c54\/TTransit-de-lISS-au-dessus-du-Pic-de-Chateau-Renard-web.jpg\" title=\"Transit de l\u2019ISS au dessus du Pic de Chateau Renard (Mickael Coulon)\" data-rl_title=\"Transit de l\u2019ISS au dessus du Pic de Chateau Renard (Mickael Coulon)\" class=\"rl-gallery-link\" data-rl_caption=\"Panorama pris lors de mon pr\u00e9c\u00e9dent s\u00e9jour en septembre 2023 \u00e0 l&apos;observatoire de St V\u00e9ran , Le Pic de Ch\u00e2teau Renard surplombe l&apos;observatoire et j&apos;y \u00e9tais mont\u00e9 pour photographier la Voie Lact\u00e9e, cette prise de vue n&apos;\u00e9tait pas du tout pr\u00e9vue ! Je n&apos;ai vu l&apos;ISS que lorsqu&apos;il a quitt\u00e9 l&apos;horizon et voulant faire un panorama de ce genre depuis un moment, j&apos;ai saut\u00e9 sur l&apos;occasion ! L&apos;ISS quitte l&apos;horizon, filant \u00e0 28000km\/h , avec \u00e0 son bord plusieurs astronautes, au dessus du village de | Date: 19.09.2023 | Prise de vue au Canon 6d, Samyang 35mm sur rotule panoramique Ninja Nodal Le tout a ensuite \u00e9t\u00e9 assembl\u00e9 sous Autopano et trait\u00e9 sous Photoshop | Photo : Mickael Coulon - Concours photo Stelvision\" data-rel=\"lightbox-gallery-3\"><img decoding=\"async\" src=\"https:\/\/www.stelvision.com\/astro\/wp-content\/uploads\/fv-contest\/c54\/TTransit-de-lISS-au-dessus-du-Pic-de-Chateau-Renard-web.jpg\" width=\"768\" height=\"384\" alt=\"Photo Transit de l&apos;ISS au dessus du Pic de Chateau Renard\" \/><span class=\"rl-gallery-caption\"><span class=\"rl-gallery-item-title\">Transit de l&rsquo;ISS au dessus du Pic de Chateau Renard (Mickael Coulon)<\/span><\/span><\/a> <\/div> <\/div> <div class=\"rl-gallery-item\" > <div class=\"rl-gallery-item-content\"> <a href=\"https:\/\/www.stelvision.com\/astro\/wp-content\/uploads\/fv-contest\/c54\/2023-10-03_215014_DSC_3394_small.jpg\" title=\"La Lune \u00e0 New-York? H\u00e9 non, ici c\u2019est Paris! (Gwenael BLANCK)\" data-rl_title=\"La Lune \u00e0 New-York? H\u00e9 non, ici c\u2019est Paris! (Gwenael BLANCK)\" class=\"rl-gallery-link\" data-rl_caption=\"Lever de Lune derri\u00e8re la r\u00e9plique de la Statue de la Libert\u00e9 de l&apos;\u00eele aux cygnes, \u00e0 Paris. Une bonne planification est n\u00e9cessaire pour r\u00e9aliser ce genre de clich\u00e9, et le spectacle toujours au rendez-vous. | Date: 3.10.2023 | Nikon Z6 + FTZ2 + Sigma 100-400 Contemporary. 400mm \/ f8 \/ ISO500 \/ 1-20eme de secondes de pose. | Photo : Gwenael BLANCK - Concours photo Stelvision\" data-rel=\"lightbox-gallery-3\"><img decoding=\"async\" src=\"https:\/\/www.stelvision.com\/astro\/wp-content\/uploads\/fv-contest\/c54\/2023-10-03_215014_DSC_3394_small.jpg\" width=\"768\" height=\"1152\" alt=\"Photo La Lune \u00e0 New-York? H\u00e9 non, ici c&apos;est Paris!\" \/><span class=\"rl-gallery-caption\"><span class=\"rl-gallery-item-title\">La Lune \u00e0 New-York? H\u00e9 non, ici c&rsquo;est Paris! (Gwenael BLANCK)<\/span><\/span><\/a> <\/div> <\/div> <\/div> <\/div> <\/p>\n\n\n\t\t\t\t\t\t<div style=\"margin-bottom: 18px;\">\t\t\t\t<a rel=\"nofollow\" href=\"https:\/\/www.stelvision.com\/astro\/boutique\/le-ciel-au-telescope\/?ref=bottom\">\r\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.stelvision.com\/astro\/wp-content\/uploads\/2025\/10\/Ciel-au-telescope-1200x900-1.webp\" alt=\"visuel publicitaire livre le Ciel au t\u00e9lescope\" class=\"img-responsive\">\r\n\t\t\t\t<\/a>\r\n\t\t\t\t<p style=\"text-align: center; margin-bottom: 0em; margin-top: 0.25em;\"><strong><a rel=\"nofollow\" href=\"https:\/\/www.stelvision.com\/astro\/boutique\/le-ciel-au-telescope\/?ref=bottom\">Le Ciel au t\u00e9lescope, le guide indispensable pour r\u00e9ussir vos observations<\/a><\/strong><\/p>\r\n\t\t\t<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Offrez-vous un moment d&rsquo;\u00e9vasion gr\u00e2ce aux images que nous envoient les astrophotographes ! Les trois galeries \u00e0 d\u00e9couvrir ci-dessous sont renouvel\u00e9es progressivement avec les photos <a href=\"https:\/\/www.stelvision.com\/astro\/galeries-photo\/\" class=\"more-link\">&#8230;<span class=\"screen-reader-text\">  Les plus belles photos astronomiques du concours Stelvision<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-8696","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Les plus belles photos astronomiques du concours Stelvision<\/title>\n<meta name=\"description\" content=\"Voici les plus belles images astronomiques re\u00e7ues de la communaut\u00e9 des astrophotographes qui participent \u00e0 notre concours photo semestriel.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.stelvision.com\/astro\/galeries-photo\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les plus belles photos astronomiques du concours Stelvision\" \/>\n<meta property=\"og:description\" content=\"Voici les plus belles images astronomiques re\u00e7ues de la communaut\u00e9 des astrophotographes qui participent \u00e0 notre concours photo semestriel.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.stelvision.com\/astro\/galeries-photo\/\" \/>\n<meta property=\"og:site_name\" content=\"Stelvision\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Stelvision\/100063368192331\/\" \/>\n<meta property=\"article:modified_time\" content=\"2023-04-27T12:33:30+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.stelvision.com\\\/astro\\\/galeries-photo\\\/\",\"url\":\"https:\\\/\\\/www.stelvision.com\\\/astro\\\/galeries-photo\\\/\",\"name\":\"Les plus belles photos astronomiques du concours Stelvision\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.stelvision.com\\\/astro\\\/#website\"},\"datePublished\":\"2019-09-24T13:24:40+00:00\",\"dateModified\":\"2023-04-27T12:33:30+00:00\",\"description\":\"Voici les plus belles images astronomiques re\u00e7ues de la communaut\u00e9 des astrophotographes qui participent \u00e0 notre concours photo semestriel.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.stelvision.com\\\/astro\\\/galeries-photo\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.stelvision.com\\\/astro\\\/galeries-photo\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.stelvision.com\\\/astro\\\/galeries-photo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.stelvision.com\\\/astro\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Les plus belles photos astronomiques du concours Stelvision\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.stelvision.com\\\/astro\\\/#website\",\"url\":\"https:\\\/\\\/www.stelvision.com\\\/astro\\\/\",\"name\":\"Stelvision\",\"description\":\"conseils, livres et mat\u00e9riel d&#039;observation du ciel\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.stelvision.com\\\/astro\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.stelvision.com\\\/astro\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.stelvision.com\\\/astro\\\/#organization\",\"name\":\"Stelvision\",\"url\":\"https:\\\/\\\/www.stelvision.com\\\/astro\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.stelvision.com\\\/astro\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.stelvision.com\\\/astro\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/logo_lisse_bleu_Stelvision_600.png\",\"contentUrl\":\"https:\\\/\\\/www.stelvision.com\\\/astro\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/logo_lisse_bleu_Stelvision_600.png\",\"width\":600,\"height\":277,\"caption\":\"Stelvision\"},\"image\":{\"@id\":\"https:\\\/\\\/www.stelvision.com\\\/astro\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Stelvision\\\/100063368192331\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Les plus belles photos astronomiques du concours Stelvision","description":"Voici les plus belles images astronomiques re\u00e7ues de la communaut\u00e9 des astrophotographes qui participent \u00e0 notre concours photo semestriel.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.stelvision.com\/astro\/galeries-photo\/","og_locale":"fr_FR","og_type":"article","og_title":"Les plus belles photos astronomiques du concours Stelvision","og_description":"Voici les plus belles images astronomiques re\u00e7ues de la communaut\u00e9 des astrophotographes qui participent \u00e0 notre concours photo semestriel.","og_url":"https:\/\/www.stelvision.com\/astro\/galeries-photo\/","og_site_name":"Stelvision","article_publisher":"https:\/\/www.facebook.com\/people\/Stelvision\/100063368192331\/","article_modified_time":"2023-04-27T12:33:30+00:00","twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.stelvision.com\/astro\/galeries-photo\/","url":"https:\/\/www.stelvision.com\/astro\/galeries-photo\/","name":"Les plus belles photos astronomiques du concours Stelvision","isPartOf":{"@id":"https:\/\/www.stelvision.com\/astro\/#website"},"datePublished":"2019-09-24T13:24:40+00:00","dateModified":"2023-04-27T12:33:30+00:00","description":"Voici les plus belles images astronomiques re\u00e7ues de la communaut\u00e9 des astrophotographes qui participent \u00e0 notre concours photo semestriel.","breadcrumb":{"@id":"https:\/\/www.stelvision.com\/astro\/galeries-photo\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.stelvision.com\/astro\/galeries-photo\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.stelvision.com\/astro\/galeries-photo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.stelvision.com\/astro\/"},{"@type":"ListItem","position":2,"name":"Les plus belles photos astronomiques du concours Stelvision"}]},{"@type":"WebSite","@id":"https:\/\/www.stelvision.com\/astro\/#website","url":"https:\/\/www.stelvision.com\/astro\/","name":"Stelvision","description":"conseils, livres et mat\u00e9riel d&#039;observation du ciel","publisher":{"@id":"https:\/\/www.stelvision.com\/astro\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.stelvision.com\/astro\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.stelvision.com\/astro\/#organization","name":"Stelvision","url":"https:\/\/www.stelvision.com\/astro\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.stelvision.com\/astro\/#\/schema\/logo\/image\/","url":"https:\/\/www.stelvision.com\/astro\/wp-content\/uploads\/2019\/03\/logo_lisse_bleu_Stelvision_600.png","contentUrl":"https:\/\/www.stelvision.com\/astro\/wp-content\/uploads\/2019\/03\/logo_lisse_bleu_Stelvision_600.png","width":600,"height":277,"caption":"Stelvision"},"image":{"@id":"https:\/\/www.stelvision.com\/astro\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Stelvision\/100063368192331\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.stelvision.com\/astro\/wp-json\/wp\/v2\/pages\/8696","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.stelvision.com\/astro\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.stelvision.com\/astro\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.stelvision.com\/astro\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.stelvision.com\/astro\/wp-json\/wp\/v2\/comments?post=8696"}],"version-history":[{"count":34,"href":"https:\/\/www.stelvision.com\/astro\/wp-json\/wp\/v2\/pages\/8696\/revisions"}],"predecessor-version":[{"id":53785,"href":"https:\/\/www.stelvision.com\/astro\/wp-json\/wp\/v2\/pages\/8696\/revisions\/53785"}],"wp:attachment":[{"href":"https:\/\/www.stelvision.com\/astro\/wp-json\/wp\/v2\/media?parent=8696"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}